{"id":404035,"date":"2026-05-13T11:53:10","date_gmt":"2026-05-13T04:53:10","guid":{"rendered":"https:\/\/specphone.com\/web\/?p=404035"},"modified":"2026-05-13T11:53:25","modified_gmt":"2026-05-13T04:53:25","slug":"launch-sony-xperia-1-viii-new-design-2026","status":"publish","type":"post","link":"https:\/\/specphone.com\/web\/launch-sony-xperia-1-viii-new-design-2026\/404035","title":{"rendered":"\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27 Sony Xperia 1 VIII \u0e1b\u0e23\u0e31\u0e1a\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e43\u0e2b\u0e21\u0e48 \u0e2d\u0e31\u0e1b\u0e40\u0e01\u0e23\u0e14\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e40\u0e17\u0e40\u0e25\u0e42\u0e1f\u0e42\u0e15\u0e49 48MP \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e0a\u0e34\u0e1b Snapdragon 8 Elite Gen 5"},"content":{"rendered":"\n<p>Sony \u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27\u0e21\u0e37\u0e2d\u0e16\u0e37\u0e2d\u0e40\u0e23\u0e37\u0e2d\u0e18\u0e07\u0e23\u0e38\u0e48\u0e19\u0e43\u0e2b\u0e21\u0e48\u0e25\u0e48\u0e32\u0e2a\u0e38\u0e14\u0e2d\u0e22\u0e48\u0e32\u0e07 <a href=\"https:\/\/specphone.com\/web\/leaks-sale-sony-xperia-1-viii-on-amezon\/403877\">Sony Xperia 1 VIII<\/a> \u0e2d\u0e2d\u0e01\u0e21\u0e32\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e25\u0e49\u0e27 \u0e0b\u0e36\u0e48\u0e07\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e01\u0e47\u0e40\u0e1b\u0e47\u0e19\u0e44\u0e1b\u0e15\u0e32\u0e21\u0e04\u0e32\u0e14\u0e08\u0e32\u0e01\u0e02\u0e48\u0e32\u0e27\u0e25\u0e37\u0e2d\u0e01\u0e48\u0e2d\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e19\u0e35\u0e49 \u0e27\u0e48\u0e32\u0e08\u0e30\u0e21\u0e35\u0e01\u0e32\u0e23\u0e2d\u0e31\u0e1b\u0e40\u0e01\u0e23\u0e14\u0e43\u0e19\u0e2b\u0e25\u0e32\u0e22\u0e46 \u0e14\u0e49\u0e32\u0e19 \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e2a\u0e40\u0e1b\u0e04\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e0a\u0e34\u0e1b\u0e1b\u0e23\u0e30\u0e21\u0e27\u0e25\u0e1c\u0e25 \u0e01\u0e25\u0e49\u0e2d\u0e07 \u0e41\u0e25\u0e30\u0e17\u0e35\u0e48\u0e40\u0e2b\u0e47\u0e19\u0e44\u0e14\u0e49\u0e0a\u0e31\u0e14\u0e40\u0e08\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e01\u0e47\u0e04\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e43\u0e2b\u0e21\u0e48 \u0e41\u0e15\u0e48\u0e23\u0e32\u0e04\u0e32\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27\u0e2d\u0e2d\u0e01\u0e21\u0e32\u0e19\u0e35\u0e49\u0e01\u0e47\u0e40\u0e23\u0e35\u0e22\u0e01\u0e44\u0e14\u0e49\u0e27\u0e48\u0e32\u0e44\u0e1b\u0e44\u0e01\u0e25\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e40\u0e01\u0e34\u0e19 \u0e14\u0e49\u0e27\u0e22\u0e23\u0e32\u0e04\u0e32\u0e23\u0e38\u0e48\u0e19\u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19\u0e08\u0e32\u0e01\u0e1d\u0e31\u0e48\u0e07\u0e22\u0e38\u0e42\u0e23\u0e1b\u0e44\u0e1b\u0e16\u0e36\u0e07 57,000 \u0e1a\u0e32\u0e17\u0e41\u0e25\u0e49\u0e27<\/p>\n\n\n\n<p>\u0e2a\u0e48\u0e27\u0e19\u0e23\u0e38\u0e48\u0e19\u0e17\u0e35\u0e48\u0e27\u0e32\u0e07\u0e02\u0e32\u0e22\u0e43\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e23\u0e32\u0e15\u0e2d\u0e19\u0e19\u0e35\u0e49\u0e01\u0e47\u0e04\u0e37\u0e2d\u00a0<strong>Sony Xperia 1 VII \u0e23\u0e32\u0e04\u0e32 35,990 \u0e1a\u0e32\u0e17<\/strong>\u00a0\u0e2a\u0e31\u0e48\u0e07\u0e0b\u0e37\u0e49\u0e2d\u0e44\u0e14\u0e49\u0e17\u0e35\u0e48\u00a0<a href=\"https:\/\/goeco.asia\/97JpBBlY\" target=\"_blank\" rel=\"noreferrer noopener\">Shopee<\/a>\/\u00a0<a href=\"https:\/\/goeco.asia\/Yi66hhoL\" target=\"_blank\" rel=\"noreferrer noopener\">Lazada<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u0e2a\u0e40\u0e1b\u0e04 Sony Xperia 1 VIII<\/h2>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"741\" height=\"450\" src=\"https:\/\/specphone.com\/web\/wp-content\/uploads\/2026\/05\/\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27-Sony-Xperia-1-VIII-\u0e1b\u0e23\u0e31\u0e1a\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e43\u0e2b\u0e21\u0e48-\u0e2d\u0e31\u0e1b\u0e40\u0e01\u0e23\u0e14\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e40\u0e17\u0e40\u0e25\u0e42\u0e1f\u0e42\u0e15\u0e49-48MP-\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e0a\u0e34\u0e1b-Snapdragon-8-Elite-Gen-5-2.jpg\" alt=\"\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27 Sony Xperia 1 VIII \u0e1b\u0e23\u0e31\u0e1a\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e43\u0e2b\u0e21\u0e48 \u0e2d\u0e31\u0e1b\u0e40\u0e01\u0e23\u0e14\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e40\u0e17\u0e40\u0e25\u0e42\u0e1f\u0e42\u0e15\u0e49 48MP \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e0a\u0e34\u0e1b Snapdragon 8 Elite Gen 5 \" class=\"wp-image-404037\" srcset=\"https:\/\/specphone.com\/web\/wp-content\/uploads\/2026\/05\/\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27-Sony-Xperia-1-VIII-\u0e1b\u0e23\u0e31\u0e1a\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e43\u0e2b\u0e21\u0e48-\u0e2d\u0e31\u0e1b\u0e40\u0e01\u0e23\u0e14\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e40\u0e17\u0e40\u0e25\u0e42\u0e1f\u0e42\u0e15\u0e49-48MP-\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e0a\u0e34\u0e1b-Snapdragon-8-Elite-Gen-5-2.jpg 741w, https:\/\/specphone.com\/web\/wp-content\/uploads\/2026\/05\/\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27-Sony-Xperia-1-VIII-\u0e1b\u0e23\u0e31\u0e1a\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e43\u0e2b\u0e21\u0e48-\u0e2d\u0e31\u0e1b\u0e40\u0e01\u0e23\u0e14\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e40\u0e17\u0e40\u0e25\u0e42\u0e1f\u0e42\u0e15\u0e49-48MP-\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e0a\u0e34\u0e1b-Snapdragon-8-Elite-Gen-5-2-300x182.jpg 300w, https:\/\/specphone.com\/web\/wp-content\/uploads\/2026\/05\/\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27-Sony-Xperia-1-VIII-\u0e1b\u0e23\u0e31\u0e1a\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e43\u0e2b\u0e21\u0e48-\u0e2d\u0e31\u0e1b\u0e40\u0e01\u0e23\u0e14\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e40\u0e17\u0e40\u0e25\u0e42\u0e1f\u0e42\u0e15\u0e49-48MP-\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e0a\u0e34\u0e1b-Snapdragon-8-Elite-Gen-5-2-150x91.jpg 150w, https:\/\/specphone.com\/web\/wp-content\/uploads\/2026\/05\/\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27-Sony-Xperia-1-VIII-\u0e1b\u0e23\u0e31\u0e1a\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e43\u0e2b\u0e21\u0e48-\u0e2d\u0e31\u0e1b\u0e40\u0e01\u0e23\u0e14\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e40\u0e17\u0e40\u0e25\u0e42\u0e1f\u0e42\u0e15\u0e49-48MP-\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e0a\u0e34\u0e1b-Snapdragon-8-Elite-Gen-5-2-450x273.jpg 450w\" sizes=\"(max-width: 741px) 100vw, 741px\" \/><\/figure>\n<\/div>\n\n\n<p>\u0e15\u0e49\u0e2d\u0e07\u0e1a\u0e2d\u0e01\u0e27\u0e48\u0e32\u0e08\u0e38\u0e14\u0e40\u0e14\u0e48\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e02\u0e2d\u0e07\u0e23\u0e38\u0e48\u0e19\u0e19\u0e35\u0e49\u0e01\u0e47\u0e04\u0e37\u0e2d\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e17\u0e33\u0e07\u0e32\u0e19\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a AI \u0e17\u0e35\u0e48\u0e0a\u0e37\u0e48\u0e2d AI Camera Assistant \u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e42\u0e14\u0e22 Xperia Intelligence \u0e0b\u0e36\u0e48\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e19\u0e35\u0e49\u0e08\u0e30\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e15\u0e31\u0e27\u0e41\u0e1a\u0e1a\u0e41\u0e25\u0e30\u0e2a\u0e20\u0e32\u0e1e\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e41\u0e19\u0e30\u0e19\u0e33\u0e01\u0e32\u0e23\u0e15\u0e31\u0e49\u0e07\u0e04\u0e48\u0e32\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14 \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e42\u0e17\u0e19\u0e2a\u0e35 \u0e01\u0e32\u0e23\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e40\u0e25\u0e19\u0e2a\u0e4c \u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e2d\u0e1f\u0e40\u0e1f\u0e01\u0e15\u0e4c\u0e2b\u0e19\u0e49\u0e32\u0e0a\u0e31\u0e14\u0e2b\u0e25\u0e31\u0e07\u0e40\u0e1a\u0e25\u0e2d\u0e41\u0e1a\u0e1a Bokeh \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49\u0e22\u0e31\u0e07\u0e21\u0e35\u0e01\u0e32\u0e23\u0e1c\u0e2a\u0e32\u0e19\u0e23\u0e27\u0e21\u0e42\u0e1b\u0e23\u0e44\u0e1f\u0e25\u0e4c\u0e2a\u0e35\u0e40\u0e1b\u0e47\u0e19 Creative Look \u0e15\u0e32\u0e21\u0e2a\u0e44\u0e15\u0e25\u0e4c\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e42\u0e1b\u0e23\u0e0b\u0e35\u0e23\u0e35\u0e2a\u0e4c Alpha \u0e02\u0e2d\u0e07\u0e17\u0e32\u0e07 Sony \u0e43\u0e2b\u0e49\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e1b\u0e23\u0e31\u0e1a\u0e41\u0e15\u0e48\u0e07\u0e15\u0e32\u0e21\u0e43\u0e08\u0e0a\u0e2d\u0e1a\u0e2d\u0e35\u0e01\u0e14\u0e49\u0e27\u0e22<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"743\" height=\"450\" src=\"https:\/\/specphone.com\/web\/wp-content\/uploads\/2026\/05\/\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27-Sony-Xperia-1-VIII-\u0e1b\u0e23\u0e31\u0e1a\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e43\u0e2b\u0e21\u0e48-\u0e2d\u0e31\u0e1b\u0e40\u0e01\u0e23\u0e14\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e40\u0e17\u0e40\u0e25\u0e42\u0e1f\u0e42\u0e15\u0e49-48MP-\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e0a\u0e34\u0e1b-Snapdragon-8-Elite-Gen-5-3.jpg\" alt=\"\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27 Sony Xperia 1 VIII \u0e1b\u0e23\u0e31\u0e1a\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e43\u0e2b\u0e21\u0e48 \u0e2d\u0e31\u0e1b\u0e40\u0e01\u0e23\u0e14\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e40\u0e17\u0e40\u0e25\u0e42\u0e1f\u0e42\u0e15\u0e49 48MP \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e0a\u0e34\u0e1b Snapdragon 8 Elite Gen 5 \" class=\"wp-image-404038\" srcset=\"https:\/\/specphone.com\/web\/wp-content\/uploads\/2026\/05\/\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27-Sony-Xperia-1-VIII-\u0e1b\u0e23\u0e31\u0e1a\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e43\u0e2b\u0e21\u0e48-\u0e2d\u0e31\u0e1b\u0e40\u0e01\u0e23\u0e14\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e40\u0e17\u0e40\u0e25\u0e42\u0e1f\u0e42\u0e15\u0e49-48MP-\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e0a\u0e34\u0e1b-Snapdragon-8-Elite-Gen-5-3.jpg 743w, https:\/\/specphone.com\/web\/wp-content\/uploads\/2026\/05\/\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27-Sony-Xperia-1-VIII-\u0e1b\u0e23\u0e31\u0e1a\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e43\u0e2b\u0e21\u0e48-\u0e2d\u0e31\u0e1b\u0e40\u0e01\u0e23\u0e14\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e40\u0e17\u0e40\u0e25\u0e42\u0e1f\u0e42\u0e15\u0e49-48MP-\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e0a\u0e34\u0e1b-Snapdragon-8-Elite-Gen-5-3-300x182.jpg 300w, https:\/\/specphone.com\/web\/wp-content\/uploads\/2026\/05\/\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27-Sony-Xperia-1-VIII-\u0e1b\u0e23\u0e31\u0e1a\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e43\u0e2b\u0e21\u0e48-\u0e2d\u0e31\u0e1b\u0e40\u0e01\u0e23\u0e14\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e40\u0e17\u0e40\u0e25\u0e42\u0e1f\u0e42\u0e15\u0e49-48MP-\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e0a\u0e34\u0e1b-Snapdragon-8-Elite-Gen-5-3-150x91.jpg 150w, https:\/\/specphone.com\/web\/wp-content\/uploads\/2026\/05\/\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27-Sony-Xperia-1-VIII-\u0e1b\u0e23\u0e31\u0e1a\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e43\u0e2b\u0e21\u0e48-\u0e2d\u0e31\u0e1b\u0e40\u0e01\u0e23\u0e14\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e40\u0e17\u0e40\u0e25\u0e42\u0e1f\u0e42\u0e15\u0e49-48MP-\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e0a\u0e34\u0e1b-Snapdragon-8-Elite-Gen-5-3-450x273.jpg 450w\" sizes=\"(max-width: 743px) 100vw, 743px\" \/><\/figure>\n<\/div>\n\n\n<p>\u0e42\u0e14\u0e22\u0e2a\u0e40\u0e1b\u0e04\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e02\u0e2d\u0e07 Sony Xperia 1 VIII \u0e15\u0e31\u0e27\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e2d\u0e31\u0e1b\u0e40\u0e01\u0e23\u0e14\u0e21\u0e32\u0e08\u0e23\u0e34\u0e07\u0e46 \u0e40\u0e25\u0e22\u0e01\u0e47\u0e04\u0e37\u0e2d\u0e40\u0e25\u0e19\u0e2a\u0e4c Telephoto \u0e17\u0e35\u0e48\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e21\u0e32\u0e43\u0e0a\u0e49\u0e40\u0e0b\u0e47\u0e19\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e02\u0e19\u0e32\u0e14 1\/1.56 \u0e19\u0e34\u0e49\u0e27 <strong>\u0e43\u0e2b\u0e0d\u0e48\u0e01\u0e27\u0e48\u0e32\u0e40\u0e0b\u0e47\u0e19\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e23\u0e38\u0e48\u0e19\u0e01\u0e48\u0e2d\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e2d\u0e22\u0e48\u0e32\u0e07 Xperia 1 VII \u0e16\u0e36\u0e07 4 \u0e40\u0e17\u0e48\u0e32<\/strong> \u0e0a\u0e48\u0e27\u0e22\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e04\u0e27\u0e32\u0e21\u0e04\u0e21\u0e0a\u0e31\u0e14\u0e41\u0e25\u0e30\u0e40\u0e01\u0e47\u0e1a\u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e43\u0e19\u0e23\u0e30\u0e22\u0e30\u0e44\u0e01\u0e25\u0e44\u0e14\u0e49\u0e14\u0e35\u0e02\u0e36\u0e49\u0e19 \u0e15\u0e31\u0e27\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e2b\u0e25\u0e31\u0e07\u0e08\u0e30\u0e21\u0e35\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14 3 \u0e15\u0e31\u0e27 \u0e04\u0e37\u0e2d\u0e40\u0e25\u0e19\u0e2a\u0e4c\u0e2d\u0e31\u0e25\u0e15\u0e23\u0e32\u0e44\u0e27\u0e14\u0e4c 16 \u0e21\u0e21., \u0e40\u0e25\u0e19\u0e2a\u0e4c\u0e2b\u0e25\u0e31\u0e01 24 \u0e21\u0e21. \u0e41\u0e25\u0e30\u0e40\u0e25\u0e19\u0e2a\u0e4c\u0e40\u0e17\u0e40\u0e25\u0e42\u0e1f\u0e42\u0e15\u0e49 70 \u0e21\u0e21.<\/p>\n\n\n\n<p>\u0e0b\u0e36\u0e48\u0e07\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14 48MP \u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e21\u0e27\u0e25\u0e1c\u0e25\u0e20\u0e32\u0e1e\u0e41\u0e1a\u0e1a RAW multi-frame processing \u0e17\u0e35\u0e48\u0e0a\u0e48\u0e27\u0e22\u0e02\u0e22\u0e32\u0e22\u0e0a\u0e48\u0e27\u0e07\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e41\u0e2a\u0e07 Dynamic range \u0e41\u0e25\u0e30\u0e25\u0e14 Noise \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e20\u0e32\u0e1e\u0e16\u0e48\u0e32\u0e22\u0e43\u0e19\u0e17\u0e35\u0e48\u0e41\u0e2a\u0e07\u0e19\u0e49\u0e2d\u0e22\u0e1e\u0e2d\u0e46 \u0e01\u0e31\u0e1a\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e1f\u0e39\u0e25\u0e40\u0e1f\u0e23\u0e21\u0e40\u0e25\u0e22\u0e17\u0e35\u0e40\u0e14\u0e35\u0e22\u0e27 \u0e2a\u0e48\u0e27\u0e19\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e2b\u0e19\u0e49\u0e32\u0e21\u0e35 12MP \u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e16\u0e48\u0e32\u0e22\u0e27\u0e34\u0e14\u0e35\u0e42\u0e2d 4K<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"800\" height=\"450\" src=\"https:\/\/specphone.com\/web\/wp-content\/uploads\/2026\/05\/\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27-Sony-Xperia-1-VIII-\u0e1b\u0e23\u0e31\u0e1a\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e43\u0e2b\u0e21\u0e48-\u0e2d\u0e31\u0e1b\u0e40\u0e01\u0e23\u0e14\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e40\u0e17\u0e40\u0e25\u0e42\u0e1f\u0e42\u0e15\u0e49-48MP-\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e0a\u0e34\u0e1b-Snapdragon-8-Elite-Gen-5-4.jpg\" alt=\"\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27 Sony Xperia 1 VIII \u0e1b\u0e23\u0e31\u0e1a\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e43\u0e2b\u0e21\u0e48 \u0e2d\u0e31\u0e1b\u0e40\u0e01\u0e23\u0e14\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e40\u0e17\u0e40\u0e25\u0e42\u0e1f\u0e42\u0e15\u0e49 48MP \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e0a\u0e34\u0e1b Snapdragon 8 Elite Gen 5 \" class=\"wp-image-404039\" srcset=\"https:\/\/specphone.com\/web\/wp-content\/uploads\/2026\/05\/\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27-Sony-Xperia-1-VIII-\u0e1b\u0e23\u0e31\u0e1a\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e43\u0e2b\u0e21\u0e48-\u0e2d\u0e31\u0e1b\u0e40\u0e01\u0e23\u0e14\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e40\u0e17\u0e40\u0e25\u0e42\u0e1f\u0e42\u0e15\u0e49-48MP-\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e0a\u0e34\u0e1b-Snapdragon-8-Elite-Gen-5-4.jpg 800w, https:\/\/specphone.com\/web\/wp-content\/uploads\/2026\/05\/\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27-Sony-Xperia-1-VIII-\u0e1b\u0e23\u0e31\u0e1a\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e43\u0e2b\u0e21\u0e48-\u0e2d\u0e31\u0e1b\u0e40\u0e01\u0e23\u0e14\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e40\u0e17\u0e40\u0e25\u0e42\u0e1f\u0e42\u0e15\u0e49-48MP-\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e0a\u0e34\u0e1b-Snapdragon-8-Elite-Gen-5-4-300x169.jpg 300w, https:\/\/specphone.com\/web\/wp-content\/uploads\/2026\/05\/\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27-Sony-Xperia-1-VIII-\u0e1b\u0e23\u0e31\u0e1a\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e43\u0e2b\u0e21\u0e48-\u0e2d\u0e31\u0e1b\u0e40\u0e01\u0e23\u0e14\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e40\u0e17\u0e40\u0e25\u0e42\u0e1f\u0e42\u0e15\u0e49-48MP-\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e0a\u0e34\u0e1b-Snapdragon-8-Elite-Gen-5-4-768x432.jpg 768w, https:\/\/specphone.com\/web\/wp-content\/uploads\/2026\/05\/\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27-Sony-Xperia-1-VIII-\u0e1b\u0e23\u0e31\u0e1a\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e43\u0e2b\u0e21\u0e48-\u0e2d\u0e31\u0e1b\u0e40\u0e01\u0e23\u0e14\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e40\u0e17\u0e40\u0e25\u0e42\u0e1f\u0e42\u0e15\u0e49-48MP-\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e0a\u0e34\u0e1b-Snapdragon-8-Elite-Gen-5-4-150x84.jpg 150w, https:\/\/specphone.com\/web\/wp-content\/uploads\/2026\/05\/\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27-Sony-Xperia-1-VIII-\u0e1b\u0e23\u0e31\u0e1a\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e43\u0e2b\u0e21\u0e48-\u0e2d\u0e31\u0e1b\u0e40\u0e01\u0e23\u0e14\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e40\u0e17\u0e40\u0e25\u0e42\u0e1f\u0e42\u0e15\u0e49-48MP-\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e0a\u0e34\u0e1b-Snapdragon-8-Elite-Gen-5-4-450x253.jpg 450w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure>\n<\/div>\n\n\n<p>\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e15\u0e31\u0e27\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07 Sony Xperia 1 VIII \u0e21\u0e35\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e17\u0e35\u0e48\u0e40\u0e23\u0e35\u0e22\u0e01\u0e27\u0e48\u0e32 <strong>ORE design<\/strong> \u0e41\u0e25\u0e30\u0e21\u0e35\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e42\u0e21\u0e14\u0e39\u0e25\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e2b\u0e25\u0e31\u0e07\u0e43\u0e2b\u0e21\u0e48\u0e2b\u0e21\u0e14 \u0e08\u0e32\u0e01\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e19\u0e27\u0e15\u0e31\u0e49\u0e07\u0e40\u0e23\u0e35\u0e22\u0e07\u0e25\u0e07\u0e21\u0e32\u0e01\u0e47\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e42\u0e21\u0e14\u0e39\u0e25\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e2a\u0e35\u0e48\u0e40\u0e2b\u0e25\u0e35\u0e48\u0e22\u0e21\u0e08\u0e15\u0e23\u0e31\u0e2a\u0e41\u0e17\u0e19 \u0e15\u0e31\u0e27\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d OLED HDR \u0e02\u0e19\u0e32\u0e14 6.5 \u0e19\u0e34\u0e49\u0e27 \u0e04\u0e27\u0e32\u0e21\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14 FHD+ \u0e2d\u0e31\u0e15\u0e23\u0e32\u0e2a\u0e48\u0e27\u0e19\u0e08\u0e2d 19.5:9 \u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e2d\u0e31\u0e15\u0e23\u0e32\u0e23\u0e35\u0e40\u0e1f\u0e23\u0e0a\u0e40\u0e23\u0e15\u0e1b\u0e23\u0e31\u0e1a\u0e44\u0e14\u0e49\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48 1-120Hz \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e04\u0e23\u0e2d\u0e1a\u0e17\u0e31\u0e1a\u0e14\u0e49\u0e27\u0e22\u0e01\u0e23\u0e30\u0e08\u0e01 Corning Gorilla Glass Victus 2 \u0e01\u0e31\u0e19\u0e19\u0e49\u0e33\u0e01\u0e31\u0e19\u0e1d\u0e38\u0e48\u0e19\u0e17\u0e35\u0e48 IP65\/68 <\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"450\" src=\"https:\/\/specphone.com\/web\/wp-content\/uploads\/2026\/05\/\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27-Sony-Xperia-1-VIII-\u0e1b\u0e23\u0e31\u0e1a\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e43\u0e2b\u0e21\u0e48-\u0e2d\u0e31\u0e1b\u0e40\u0e01\u0e23\u0e14\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e40\u0e17\u0e40\u0e25\u0e42\u0e1f\u0e42\u0e15\u0e49-48MP-\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e0a\u0e34\u0e1b-Snapdragon-8-Elite-Gen-5-5.jpg\" alt=\"\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27 Sony Xperia 1 VIII \u0e1b\u0e23\u0e31\u0e1a\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e43\u0e2b\u0e21\u0e48 \u0e2d\u0e31\u0e1b\u0e40\u0e01\u0e23\u0e14\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e40\u0e17\u0e40\u0e25\u0e42\u0e1f\u0e42\u0e15\u0e49 48MP \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e0a\u0e34\u0e1b Snapdragon 8 Elite Gen 5 \" class=\"wp-image-404040\" srcset=\"https:\/\/specphone.com\/web\/wp-content\/uploads\/2026\/05\/\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27-Sony-Xperia-1-VIII-\u0e1b\u0e23\u0e31\u0e1a\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e43\u0e2b\u0e21\u0e48-\u0e2d\u0e31\u0e1b\u0e40\u0e01\u0e23\u0e14\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e40\u0e17\u0e40\u0e25\u0e42\u0e1f\u0e42\u0e15\u0e49-48MP-\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e0a\u0e34\u0e1b-Snapdragon-8-Elite-Gen-5-5.jpg 800w, https:\/\/specphone.com\/web\/wp-content\/uploads\/2026\/05\/\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27-Sony-Xperia-1-VIII-\u0e1b\u0e23\u0e31\u0e1a\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e43\u0e2b\u0e21\u0e48-\u0e2d\u0e31\u0e1b\u0e40\u0e01\u0e23\u0e14\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e40\u0e17\u0e40\u0e25\u0e42\u0e1f\u0e42\u0e15\u0e49-48MP-\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e0a\u0e34\u0e1b-Snapdragon-8-Elite-Gen-5-5-300x169.jpg 300w, https:\/\/specphone.com\/web\/wp-content\/uploads\/2026\/05\/\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27-Sony-Xperia-1-VIII-\u0e1b\u0e23\u0e31\u0e1a\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e43\u0e2b\u0e21\u0e48-\u0e2d\u0e31\u0e1b\u0e40\u0e01\u0e23\u0e14\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e40\u0e17\u0e40\u0e25\u0e42\u0e1f\u0e42\u0e15\u0e49-48MP-\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e0a\u0e34\u0e1b-Snapdragon-8-Elite-Gen-5-5-768x432.jpg 768w, https:\/\/specphone.com\/web\/wp-content\/uploads\/2026\/05\/\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27-Sony-Xperia-1-VIII-\u0e1b\u0e23\u0e31\u0e1a\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e43\u0e2b\u0e21\u0e48-\u0e2d\u0e31\u0e1b\u0e40\u0e01\u0e23\u0e14\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e40\u0e17\u0e40\u0e25\u0e42\u0e1f\u0e42\u0e15\u0e49-48MP-\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e0a\u0e34\u0e1b-Snapdragon-8-Elite-Gen-5-5-150x84.jpg 150w, https:\/\/specphone.com\/web\/wp-content\/uploads\/2026\/05\/\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27-Sony-Xperia-1-VIII-\u0e1b\u0e23\u0e31\u0e1a\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e43\u0e2b\u0e21\u0e48-\u0e2d\u0e31\u0e1b\u0e40\u0e01\u0e23\u0e14\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e40\u0e17\u0e40\u0e25\u0e42\u0e1f\u0e42\u0e15\u0e49-48MP-\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e0a\u0e34\u0e1b-Snapdragon-8-Elite-Gen-5-5-450x253.jpg 450w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure>\n<\/div>\n\n\n<p>\u0e2a\u0e34\u0e48\u0e07\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e22\u0e31\u0e07\u0e21\u0e35\u0e21\u0e32\u0e43\u0e2b\u0e49\u0e15\u0e32\u0e21\u0e40\u0e2d\u0e01\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c\u0e02\u0e2d\u0e07 Sony \u0e01\u0e47\u0e22\u0e31\u0e07\u0e21\u0e35\u0e43\u0e2b\u0e49\u0e04\u0e23\u0e1a\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e38\u0e48\u0e21\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e02\u0e49\u0e32\u0e07\u0e15\u0e31\u0e27\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07, \u0e0a\u0e48\u0e2d\u0e07\u0e40\u0e2a\u0e35\u0e22\u0e1a\u0e2b\u0e39\u0e1f\u0e31\u0e07 3.5 \u0e21\u0e34\u0e25\u0e25\u0e34\u0e40\u0e21\u0e15\u0e23 \u0e41\u0e25\u0e30\u0e0a\u0e48\u0e2d\u0e07\u0e43\u0e2a\u0e48 microSD \u0e17\u0e35\u0e48\u0e02\u0e22\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e08\u0e38\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14\u0e16\u0e36\u0e07 2TB \u0e14\u0e49\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e01\u0e47\u0e08\u0e31\u0e14\u0e40\u0e15\u0e47\u0e21\u0e14\u0e49\u0e27\u0e22\u0e25\u0e33\u0e42\u0e1e\u0e07\u0e04\u0e39\u0e48\u0e2a\u0e40\u0e15\u0e2d\u0e23\u0e34\u0e42\u0e2d Full-Stage \u0e17\u0e35\u0e48\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e43\u0e2b\u0e49\u0e0a\u0e38\u0e14\u0e25\u0e33\u0e42\u0e1e\u0e07\u0e0b\u0e49\u0e32\u0e22\u0e41\u0e25\u0e30\u0e02\u0e27\u0e32\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e01\u0e31\u0e19 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e40\u0e1a\u0e2a\u0e17\u0e35\u0e48\u0e25\u0e36\u0e01\u0e02\u0e36\u0e49\u0e19 \u0e40\u0e2a\u0e35\u0e22\u0e07\u0e41\u0e2b\u0e25\u0e21\u0e04\u0e21\u0e0a\u0e31\u0e14 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e17\u0e35\u0e48\u0e01\u0e27\u0e49\u0e32\u0e07\u0e2a\u0e21\u0e08\u0e23\u0e34\u0e07\u0e22\u0e34\u0e48\u0e07\u0e02\u0e36\u0e49\u0e19<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"450\" src=\"https:\/\/specphone.com\/web\/wp-content\/uploads\/2026\/05\/\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27-Sony-Xperia-1-VIII-\u0e1b\u0e23\u0e31\u0e1a\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e43\u0e2b\u0e21\u0e48-\u0e2d\u0e31\u0e1b\u0e40\u0e01\u0e23\u0e14\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e40\u0e17\u0e40\u0e25\u0e42\u0e1f\u0e42\u0e15\u0e49-48MP-\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e0a\u0e34\u0e1b-Snapdragon-8-Elite-Gen-5-6.jpg\" alt=\"\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27 Sony Xperia 1 VIII \u0e1b\u0e23\u0e31\u0e1a\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e43\u0e2b\u0e21\u0e48 \u0e2d\u0e31\u0e1b\u0e40\u0e01\u0e23\u0e14\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e40\u0e17\u0e40\u0e25\u0e42\u0e1f\u0e42\u0e15\u0e49 48MP \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e0a\u0e34\u0e1b Snapdragon 8 Elite Gen 5 \" class=\"wp-image-404041\" srcset=\"https:\/\/specphone.com\/web\/wp-content\/uploads\/2026\/05\/\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27-Sony-Xperia-1-VIII-\u0e1b\u0e23\u0e31\u0e1a\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e43\u0e2b\u0e21\u0e48-\u0e2d\u0e31\u0e1b\u0e40\u0e01\u0e23\u0e14\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e40\u0e17\u0e40\u0e25\u0e42\u0e1f\u0e42\u0e15\u0e49-48MP-\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e0a\u0e34\u0e1b-Snapdragon-8-Elite-Gen-5-6.jpg 800w, https:\/\/specphone.com\/web\/wp-content\/uploads\/2026\/05\/\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27-Sony-Xperia-1-VIII-\u0e1b\u0e23\u0e31\u0e1a\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e43\u0e2b\u0e21\u0e48-\u0e2d\u0e31\u0e1b\u0e40\u0e01\u0e23\u0e14\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e40\u0e17\u0e40\u0e25\u0e42\u0e1f\u0e42\u0e15\u0e49-48MP-\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e0a\u0e34\u0e1b-Snapdragon-8-Elite-Gen-5-6-300x169.jpg 300w, https:\/\/specphone.com\/web\/wp-content\/uploads\/2026\/05\/\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27-Sony-Xperia-1-VIII-\u0e1b\u0e23\u0e31\u0e1a\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e43\u0e2b\u0e21\u0e48-\u0e2d\u0e31\u0e1b\u0e40\u0e01\u0e23\u0e14\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e40\u0e17\u0e40\u0e25\u0e42\u0e1f\u0e42\u0e15\u0e49-48MP-\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e0a\u0e34\u0e1b-Snapdragon-8-Elite-Gen-5-6-768x432.jpg 768w, https:\/\/specphone.com\/web\/wp-content\/uploads\/2026\/05\/\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27-Sony-Xperia-1-VIII-\u0e1b\u0e23\u0e31\u0e1a\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e43\u0e2b\u0e21\u0e48-\u0e2d\u0e31\u0e1b\u0e40\u0e01\u0e23\u0e14\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e40\u0e17\u0e40\u0e25\u0e42\u0e1f\u0e42\u0e15\u0e49-48MP-\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e0a\u0e34\u0e1b-Snapdragon-8-Elite-Gen-5-6-150x84.jpg 150w, https:\/\/specphone.com\/web\/wp-content\/uploads\/2026\/05\/\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27-Sony-Xperia-1-VIII-\u0e1b\u0e23\u0e31\u0e1a\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e43\u0e2b\u0e21\u0e48-\u0e2d\u0e31\u0e1b\u0e40\u0e01\u0e23\u0e14\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e40\u0e17\u0e40\u0e25\u0e42\u0e1f\u0e42\u0e15\u0e49-48MP-\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e0a\u0e34\u0e1b-Snapdragon-8-Elite-Gen-5-6-450x253.jpg 450w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure>\n<\/div>\n\n\n<p>\u0e14\u0e49\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e Sony Xperia 1 VIII \u0e40\u0e25\u0e37\u0e2d\u0e01\u0e43\u0e0a\u0e49\u0e0a\u0e34\u0e1b\u0e15\u0e31\u0e27\u0e41\u0e23\u0e07\u0e23\u0e38\u0e48\u0e19\u0e40\u0e23\u0e37\u0e2d\u0e18\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07 Snapdragon 8 Elite Gen 5 \u0e08\u0e32\u0e01 Qualcomm \u0e0b\u0e36\u0e48\u0e07\u0e17\u0e32\u0e07 Sony \u0e40\u0e04\u0e25\u0e21\u0e27\u0e48\u0e32\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e42\u0e14\u0e22\u0e23\u0e27\u0e21\u0e44\u0e14\u0e49\u0e41\u0e23\u0e07\u0e02\u0e36\u0e49\u0e19\u0e16\u0e36\u0e07 20% \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e01\u0e31\u0e1a\u0e23\u0e38\u0e48\u0e19\u0e01\u0e48\u0e2d\u0e19 \u0e15\u0e2d\u0e1a\u0e42\u0e08\u0e17\u0e22\u0e4c\u0e17\u0e31\u0e49\u0e07\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e2b\u0e25\u0e32\u0e22\u0e46 \u0e41\u0e2d\u0e1b\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e17\u0e33\u0e04\u0e2d\u0e19\u0e40\u0e17\u0e19\u0e15\u0e4c\u0e2b\u0e19\u0e31\u0e01\u0e46 \u0e15\u0e31\u0e27\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e07\u0e32\u0e19\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a RAM \u0e41\u0e1a\u0e1a LPDDR5X \u0e02\u0e19\u0e32\u0e14 12GB \u0e2b\u0e23\u0e37\u0e2d 16GB \u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e08\u0e38\u0e41\u0e1a\u0e1a UFS 4.1 \u0e21\u0e35\u0e17\u0e31\u0e49\u0e07 256GB \u0e2b\u0e23\u0e37\u0e2d 1TB \u0e17\u0e33\u0e07\u0e32\u0e19\u0e1a\u0e19\u0e23\u0e30\u0e1a\u0e1a Android 14 \u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e31\u0e19\u0e15\u0e35\u0e01\u0e32\u0e23\u0e2d\u0e31\u0e1b\u0e40\u0e14\u0e15 OS \u0e19\u0e32\u0e19 4 \u0e1b\u0e35 \u0e41\u0e25\u0e30\u0e41\u0e1e\u0e15\u0e0a\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e22\u0e32\u0e27\u0e19\u0e32\u0e19 6 \u0e1b\u0e35<\/p>\n\n\n\n<p>\u0e2a\u0e48\u0e27\u0e19\u0e41\u0e1a\u0e15\u0e40\u0e15\u0e2d\u0e23\u0e35\u0e48\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e08\u0e38\u0e17\u0e35\u0e48 5,000mAh \u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e0a\u0e32\u0e23\u0e4c\u0e08\u0e44\u0e27\u0e1c\u0e48\u0e32\u0e19\u0e2a\u0e32\u0e22 30W \u0e41\u0e25\u0e30\u0e0a\u0e32\u0e23\u0e4c\u0e08\u0e44\u0e23\u0e49\u0e2a\u0e32\u0e22 Qi \u0e42\u0e14\u0e22 Sony \u0e23\u0e30\u0e1a\u0e38\u0e27\u0e48\u0e32\u0e41\u0e1a\u0e15\u0e40\u0e15\u0e2d\u0e23\u0e35\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e44\u0e14\u0e49\u0e22\u0e32\u0e27\u0e19\u0e32\u0e19\u0e16\u0e36\u0e07 2 \u0e27\u0e31\u0e19 \u0e41\u0e25\u0e30\u0e21\u0e35\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e16\u0e19\u0e2d\u0e21\u0e41\u0e1a\u0e15\u0e40\u0e15\u0e2d\u0e23\u0e35\u0e48\u0e43\u0e2b\u0e49\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e44\u0e14\u0e49\u0e22\u0e32\u0e27\u0e19\u0e32\u0e19\u0e16\u0e36\u0e07 4 \u0e1b\u0e35 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e23\u0e30\u0e1a\u0e1a Processing Optimization \u0e17\u0e35\u0e48\u0e0a\u0e48\u0e27\u0e22\u0e25\u0e14\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e1b\u0e34\u0e14\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e41\u0e2d\u0e1b\u0e17\u0e35\u0e48\u0e01\u0e34\u0e19\u0e2a\u0e40\u0e1b\u0e04\u0e2b\u0e19\u0e31\u0e01\u0e46 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e0a\u0e48\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e19\u0e33\u0e17\u0e32\u0e07\u0e2b\u0e23\u0e37\u0e2d Maps<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u0e23\u0e32\u0e04\u0e32\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e27\u0e32\u0e07\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 Sony Xperia 1 VIII<\/h2>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"450\" src=\"https:\/\/specphone.com\/web\/wp-content\/uploads\/2026\/05\/\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27-Sony-Xperia-1-VIII-\u0e1b\u0e23\u0e31\u0e1a\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e43\u0e2b\u0e21\u0e48-\u0e2d\u0e31\u0e1b\u0e40\u0e01\u0e23\u0e14\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e40\u0e17\u0e40\u0e25\u0e42\u0e1f\u0e42\u0e15\u0e49-48MP-\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e0a\u0e34\u0e1b-Snapdragon-8-Elite-Gen-5-1.jpg\" alt=\"\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27 Sony Xperia 1 VIII \u0e1b\u0e23\u0e31\u0e1a\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e43\u0e2b\u0e21\u0e48 \u0e2d\u0e31\u0e1b\u0e40\u0e01\u0e23\u0e14\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e40\u0e17\u0e40\u0e25\u0e42\u0e1f\u0e42\u0e15\u0e49 48MP \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e0a\u0e34\u0e1b Snapdragon 8 Elite Gen 5 \" class=\"wp-image-404036\" srcset=\"https:\/\/specphone.com\/web\/wp-content\/uploads\/2026\/05\/\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27-Sony-Xperia-1-VIII-\u0e1b\u0e23\u0e31\u0e1a\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e43\u0e2b\u0e21\u0e48-\u0e2d\u0e31\u0e1b\u0e40\u0e01\u0e23\u0e14\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e40\u0e17\u0e40\u0e25\u0e42\u0e1f\u0e42\u0e15\u0e49-48MP-\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e0a\u0e34\u0e1b-Snapdragon-8-Elite-Gen-5-1.jpg 800w, https:\/\/specphone.com\/web\/wp-content\/uploads\/2026\/05\/\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27-Sony-Xperia-1-VIII-\u0e1b\u0e23\u0e31\u0e1a\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e43\u0e2b\u0e21\u0e48-\u0e2d\u0e31\u0e1b\u0e40\u0e01\u0e23\u0e14\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e40\u0e17\u0e40\u0e25\u0e42\u0e1f\u0e42\u0e15\u0e49-48MP-\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e0a\u0e34\u0e1b-Snapdragon-8-Elite-Gen-5-1-300x169.jpg 300w, https:\/\/specphone.com\/web\/wp-content\/uploads\/2026\/05\/\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27-Sony-Xperia-1-VIII-\u0e1b\u0e23\u0e31\u0e1a\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e43\u0e2b\u0e21\u0e48-\u0e2d\u0e31\u0e1b\u0e40\u0e01\u0e23\u0e14\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e40\u0e17\u0e40\u0e25\u0e42\u0e1f\u0e42\u0e15\u0e49-48MP-\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e0a\u0e34\u0e1b-Snapdragon-8-Elite-Gen-5-1-768x432.jpg 768w, https:\/\/specphone.com\/web\/wp-content\/uploads\/2026\/05\/\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27-Sony-Xperia-1-VIII-\u0e1b\u0e23\u0e31\u0e1a\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e43\u0e2b\u0e21\u0e48-\u0e2d\u0e31\u0e1b\u0e40\u0e01\u0e23\u0e14\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e40\u0e17\u0e40\u0e25\u0e42\u0e1f\u0e42\u0e15\u0e49-48MP-\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e0a\u0e34\u0e1b-Snapdragon-8-Elite-Gen-5-1-150x84.jpg 150w, https:\/\/specphone.com\/web\/wp-content\/uploads\/2026\/05\/\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27-Sony-Xperia-1-VIII-\u0e1b\u0e23\u0e31\u0e1a\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e43\u0e2b\u0e21\u0e48-\u0e2d\u0e31\u0e1b\u0e40\u0e01\u0e23\u0e14\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e40\u0e17\u0e40\u0e25\u0e42\u0e1f\u0e42\u0e15\u0e49-48MP-\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e0a\u0e34\u0e1b-Snapdragon-8-Elite-Gen-5-1-450x253.jpg 450w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure>\n<\/div>\n\n\n<p>Sony Xperia 1 VIII \u0e21\u0e35\u0e43\u0e2b\u0e49\u0e40\u0e25\u0e37\u0e2d\u0e01 4 \u0e2a\u0e35 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 <strong>\u0e2a\u0e35\u0e14\u0e33 Graphite Black, \u0e2a\u0e35\u0e40\u0e07\u0e34\u0e19 Iolite Silver, \u0e2a\u0e35\u0e41\u0e14\u0e07 Garnet Red \u0e41\u0e25\u0e30\u0e2a\u0e35\u0e17\u0e2d\u0e07 Native Gold<\/strong> \u0e42\u0e14\u0e22\u0e17\u0e32\u0e07 <a href=\"https:\/\/www.sony.co.uk\/smartphones\/products\/xperia-1m8\/buy\" target=\"_blank\" rel=\"noopener\">Sony<\/a> \u0e44\u0e14\u0e49\u0e40\u0e23\u0e34\u0e48\u0e21\u0e40\u0e1b\u0e34\u0e14\u0e43\u0e2b\u0e49\u0e2a\u0e31\u0e48\u0e07\u0e08\u0e2d\u0e07\u0e25\u0e48\u0e27\u0e07\u0e2b\u0e19\u0e49\u0e32\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e25\u0e49\u0e27\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 13 \u0e1e\u0e24\u0e29\u0e20\u0e32\u0e04\u0e21 2026 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e19\u0e44\u0e1b\u0e04\u0e23\u0e31\u0e1a \u0e2a\u0e48\u0e27\u0e19\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e04\u0e07\u0e15\u0e49\u0e2d\u0e07\u0e23\u0e2d\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e02\u0e48\u0e32\u0e27\u0e2d\u0e31\u0e1b\u0e40\u0e14\u0e15\u0e27\u0e31\u0e19\u0e27\u0e32\u0e07\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e35\u0e01\u0e04\u0e23\u0e31\u0e49\u0e07 \u0e41\u0e25\u0e30\u0e21\u0e35\u0e23\u0e32\u0e04\u0e32\u0e02\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e25\u0e30\u0e23\u0e38\u0e48\u0e19\u0e14\u0e31\u0e07\u0e19\u0e35\u0e49<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>\u0e23\u0e38\u0e48\u0e19\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e04\u0e27\u0e32\u0e21\u0e08\u0e38 256GB:<\/strong> \u0e23\u0e32\u0e04\u0e32\u0e43\u0e19\u0e22\u0e38\u0e42\u0e23\u0e1b 1,499 \u0e22\u0e39\u0e42\u0e23 \u0e2b\u0e23\u0e37\u0e2d\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 57,000 \u0e1a\u0e32\u0e17 \u0e2a\u0e31\u0e48\u0e07\u0e08\u0e2d\u0e07\u0e25\u0e48\u0e27\u0e07\u0e2b\u0e19\u0e49\u0e32\u0e43\u0e19\u0e23\u0e2d\u0e1a\u0e41\u0e23\u0e01\u0e08\u0e30\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2b\u0e39\u0e1f\u0e31\u0e07\u0e04\u0e23\u0e2d\u0e1a\u0e2b\u0e39\u0e23\u0e38\u0e48\u0e19\u0e43\u0e2b\u0e21\u0e48\u0e25\u0e48\u0e32\u0e2a\u0e38\u0e14\u0e2d\u0e22\u0e48\u0e32\u0e07 Sony WH-1000XM6<\/li>\n\n\n\n<li><strong>\u0e23\u0e38\u0e48\u0e19\u0e1e\u0e34\u0e40\u0e28\u0e29 Exclusive Edition \u0e04\u0e27\u0e32\u0e21\u0e08\u0e38 1TB:<\/strong> \u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e35\u0e17\u0e2d\u0e07 Native Gold \u0e27\u0e32\u0e07\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e02\u0e2d\u0e07 Sony \u0e43\u0e19\u0e1a\u0e32\u0e07\u0e20\u0e39\u0e21\u0e34\u0e20\u0e32\u0e04\u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19 \u0e21\u0e35\u0e23\u0e32\u0e04\u0e32\u0e2d\u0e22\u0e39\u0e48\u0e17\u0e35\u0e48 1,999 \u0e22\u0e39\u0e42\u0e23 \u0e2b\u0e23\u0e37\u0e2d\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 76,000 \u0e1a\u0e32\u0e17)<\/li>\n<\/ul>\n\n\n\n<p>\u0e17\u0e35\u0e48\u0e21\u0e32: <a href=\"https:\/\/www.fonearena.com\/blog\/482521\/sony-xperia-1-viii-price-specifications.html\" target=\"_blank\" rel=\"noopener\">fonearena<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27 Sony Xperia 1 VIII \u0e17\u0e35\u0e48\u0e21\u0e35\u0e01\u0e32\u0e23\u0e2d\u0e31\u0e1b\u0e40\u0e01\u0e23\u0e14\u0e43\u0e19\u0e2b\u0e25\u0e32\u0e22\u0e46 \u0e14\u0e49\u0e32\u0e19 \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e0a\u0e34\u0e1b \u0e01\u0e25\u0e49\u0e2d\u0e07 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e43\u0e2b\u0e21\u0e48 \u0e41\u0e15\u0e48\u0e23\u0e32\u0e04\u0e32\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27\u0e2d\u0e2d\u0e01\u0e21\u0e32\u0e19\u0e35\u0e49\u0e01\u0e47\u0e40\u0e23\u0e35\u0e22\u0e01\u0e44\u0e14\u0e49\u0e27\u0e48\u0e32\u0e44\u0e1b\u0e44\u0e01\u0e25\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e40\u0e01\u0e34\u0e19 \u0e14\u0e49\u0e27\u0e22\u0e23\u0e32\u0e04\u0e32\u0e23\u0e38\u0e48\u0e19\u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19\u0e08\u0e32\u0e01\u0e1d\u0e31\u0e48\u0e07\u0e22\u0e38\u0e42\u0e23\u0e1b\u0e44\u0e1b\u0e16\u0e36\u0e07 57,000 \u0e1a\u0e32\u0e17\u0e41\u0e25\u0e49\u0e27<\/p>\n","protected":false},"author":59,"featured_media":404042,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5573,16],"tags":[109,12552],"class_list":{"0":"post-404035","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-news","8":"category-android-news","9":"tag-sony","10":"tag-sony-xperia-1-viii"},"_links":{"self":[{"href":"https:\/\/specphone.com\/web\/wp-json\/wp\/v2\/posts\/404035","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/specphone.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/specphone.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/specphone.com\/web\/wp-json\/wp\/v2\/users\/59"}],"replies":[{"embeddable":true,"href":"https:\/\/specphone.com\/web\/wp-json\/wp\/v2\/comments?post=404035"}],"version-history":[{"count":2,"href":"https:\/\/specphone.com\/web\/wp-json\/wp\/v2\/posts\/404035\/revisions"}],"predecessor-version":[{"id":404050,"href":"https:\/\/specphone.com\/web\/wp-json\/wp\/v2\/posts\/404035\/revisions\/404050"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/specphone.com\/web\/wp-json\/wp\/v2\/media\/404042"}],"wp:attachment":[{"href":"https:\/\/specphone.com\/web\/wp-json\/wp\/v2\/media?parent=404035"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/specphone.com\/web\/wp-json\/wp\/v2\/categories?post=404035"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/specphone.com\/web\/wp-json\/wp\/v2\/tags?post=404035"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}